{"id":6742,"date":"2024-09-02T07:30:12","date_gmt":"2024-09-02T05:30:12","guid":{"rendered":"https:\/\/naturbett-einstreu.ch\/?p=6742"},"modified":"2024-09-02T09:46:05","modified_gmt":"2024-09-02T07:46:05","slug":"lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024","status":"publish","type":"post","link":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/","title":{"rendered":"Lit naturel<sup>\u00ae<\/sup> liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024"},"content":{"rendered":"\n<section class=\"sh-section sh-section-4b1513a403d6b8332fe8b7c4a3caa605 fw-main-row sh-section-visibility-everywhere sh-animated fadeIn\" data-wow-duration=\"2s\" >\n\t\n\t\n\t<div class=\"sh-section-container container-fluid\">\n\t\t<div class=\"fw-row\">\n\t\n<div class=\"sh-column sh-column-727a43c66a61c6684cd39d968b88e0dd fw-col-xs-12\" >\n\n\t\n\t<div class=\"sh-column-wrapper\">\n\t\t\n<div id=\"text-block-6adfc43b9a9152023ca2ff26db3f59b5\" class=\"sh-text-block\">\n\t<p>A l\u2019occasion de Cheval Passion, qui se d\u00e9roule \u00e0 l\u2019IENA du 7 au 15 septembre, nous serons pr\u00e9sents \u00e0 partir du 12 septembre avec notre stand d\u2019information. Venez voir notre stand \u00e0 l\u2019int\u00e9rieur de la grande tente situ\u00e9e pr\u00e8s du paddock de saut d\u2019obstacles et d\u00e9couvrez tout ce qu\u2019il faut savoir sur notre liti\u00e8re durable suisse, Lit naturel<sup>\u00ae <\/sup>liti\u00e8re pour chevaux.<\/p><p>Vous aurez la possibilit\u00e9 de regarder nos diff\u00e9rentes vid\u00e9os explicatives via des codes QR et de feuilleter nos dossiers afin de vous informer en d\u00e9tail sur notre produit et son entretien. Notre conseill\u00e8re de vente est elle-m\u00eame engag\u00e9e \u00e0 cette occasion \u00e0 l\u2019IENA et peut \u00eatre contact\u00e9e \u00e0 tout moment si vous souhaitez un conseil personnalis\u00e9 ou si vous voulez r\u00e9server un rendez-vous conseil directement dans votre \u00e9curie.<\/p><p>Vous n\u2019\u00eates pas s\u00fbr que notre Lit naturel<sup>\u00ae <\/sup>liti\u00e8re pour chevaux soit la bonne solution pour vos amis \u00e0 sabots\u00a0? Allez donc faire un tour \u00e0 l\u2019\u00e9curie (stabulations actives) des poneys trotteurs et constatez par vous-m\u00eame \u00e0 quel point les poneys s\u2019y sentent bien. Vous remarquerez qu\u2019aucune odeur d\u2019ammoniac ou de poussi\u00e8re n\u2019est perceptible.<\/p><p>En plus des diverses disciplines \u00e9questres, Cheval Passion propose tout ce qui concerne le cheval. D\u00e9couvrez des comp\u00e9titions passionnantes, vibrez avec les courses et profitez des activit\u00e9s vari\u00e9es pour les jeunes et les moins jeunes. L\u2019entr\u00e9e est gratuite et la restauration sur place est assur\u00e9e. Nous serions tr\u00e8s heureux de vous accueillir \u00e0 notre stand<\/p><\/div>\n\t<\/div>\n\n\n\t\t\n\n<\/div>\n<\/div>\n\n\t<\/div>\n<\/section>\n\n","protected":false},"excerpt":{"rendered":"<p>Du 12 au 15 septembre nous serons pr\u00e9sents avec notre stand \u00e0 l\u2019Institut Equestre National d\u2019Avenches.<\/p>\n","protected":false},"author":4,"featured_media":6744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-6742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-et-foires-commerciales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lukas\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Naturbett\u00ae Einstreu |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024 | Naturbett\u00ae Einstreu\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2021\/05\/naturbett-pferdeeinstreu.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2021\/05\/naturbett-pferdeeinstreu.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-02T05:30:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-02T07:46:05+00:00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#article\",\"name\":\"Lit naturel\\u00ae liti\\u00e8re pour chevaux \\u00e0 Cheval Passion 2024 | Naturbett\\u00ae Einstreu\",\"headline\":\"Lit naturel\\u00ae liti\\u00e8re pour chevaux \\u00e0 Cheval Passion 2024\",\"author\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/author\\\/lume-adx-wp2020\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Cheval-Passion_1200x675.jpg\",\"width\":1200,\"height\":675},\"datePublished\":\"2024-09-02T07:30:12+02:00\",\"dateModified\":\"2024-09-02T09:46:05+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#webpage\"},\"articleSection\":\"\\u00c9v\\u00e9nements et foires commerciales, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/news\\\/evenements-et-foires-commerciales\\\/#listItem\",\"name\":\"\\u00c9v\\u00e9nements et foires commerciales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/news\\\/evenements-et-foires-commerciales\\\/#listItem\",\"position\":2,\"name\":\"\\u00c9v\\u00e9nements et foires commerciales\",\"item\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/news\\\/evenements-et-foires-commerciales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#listItem\",\"name\":\"Lit naturel\\u00ae liti\\u00e8re pour chevaux \\u00e0 Cheval Passion 2024\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#listItem\",\"position\":3,\"name\":\"Lit naturel\\u00ae liti\\u00e8re pour chevaux \\u00e0 Cheval Passion 2024\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/news\\\/evenements-et-foires-commerciales\\\/#listItem\",\"name\":\"\\u00c9v\\u00e9nements et foires commerciales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#organization\",\"name\":\"Naturbett\\u00ae Einstreu\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/\",\"telephone\":\"+41763235656\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Naturbett-2.svg\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#organizationLogo\",\"width\":37,\"height\":12,\"caption\":\"Naturbett\\u00ae Pferdeeinstreu\"},\"image\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/author\\\/lume-adx-wp2020\\\/#author\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/author\\\/lume-adx-wp2020\\\/\",\"name\":\"Lukas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/911261500c6a593e1894937a7183763889722fa98b92dfd4acb5a53fcd72282a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lukas\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#webpage\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/\",\"name\":\"Lit naturel\\u00ae liti\\u00e8re pour chevaux \\u00e0 Cheval Passion 2024 | Naturbett\\u00ae Einstreu\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/author\\\/lume-adx-wp2020\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/author\\\/lume-adx-wp2020\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Cheval-Passion_1200x675.jpg\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#mainImage\",\"width\":1200,\"height\":675},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\\\/#mainImage\"},\"datePublished\":\"2024-09-02T07:30:12+02:00\",\"dateModified\":\"2024-09-02T09:46:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/\",\"name\":\"Naturbett\\u00ae Einstreu\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturbett-einstreu.ch\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024 | Naturbett\u00ae Einstreu","description":"","canonical_url":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#article","name":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024 | Naturbett\u00ae Einstreu","headline":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024","author":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/author\/lume-adx-wp2020\/#author"},"publisher":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2024\/08\/Cheval-Passion_1200x675.jpg","width":1200,"height":675},"datePublished":"2024-09-02T07:30:12+02:00","dateModified":"2024-09-02T09:46:05+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#webpage"},"isPartOf":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#webpage"},"articleSection":"\u00c9v\u00e9nements et foires commerciales, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/naturbett-einstreu.ch\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/news\/evenements-et-foires-commerciales\/#listItem","name":"\u00c9v\u00e9nements et foires commerciales"}},{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/news\/evenements-et-foires-commerciales\/#listItem","position":2,"name":"\u00c9v\u00e9nements et foires commerciales","item":"https:\/\/naturbett-einstreu.ch\/fr\/news\/evenements-et-foires-commerciales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#listItem","name":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024"},"previousItem":{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#listItem","position":3,"name":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024","previousItem":{"@type":"ListItem","@id":"https:\/\/naturbett-einstreu.ch\/fr\/news\/evenements-et-foires-commerciales\/#listItem","name":"\u00c9v\u00e9nements et foires commerciales"}}]},{"@type":"Organization","@id":"https:\/\/naturbett-einstreu.ch\/fr\/#organization","name":"Naturbett\u00ae Einstreu","url":"https:\/\/naturbett-einstreu.ch\/fr\/","telephone":"+41763235656","logo":{"@type":"ImageObject","url":"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2020\/04\/Naturbett-2.svg","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#organizationLogo","width":37,"height":12,"caption":"Naturbett\u00ae Pferdeeinstreu"},"image":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/naturbett-einstreu.ch\/fr\/author\/lume-adx-wp2020\/#author","url":"https:\/\/naturbett-einstreu.ch\/fr\/author\/lume-adx-wp2020\/","name":"Lukas","image":{"@type":"ImageObject","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/911261500c6a593e1894937a7183763889722fa98b92dfd4acb5a53fcd72282a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lukas"}},{"@type":"WebPage","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#webpage","url":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/","name":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024 | Naturbett\u00ae Einstreu","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#breadcrumblist"},"author":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/author\/lume-adx-wp2020\/#author"},"creator":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/author\/lume-adx-wp2020\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2024\/08\/Cheval-Passion_1200x675.jpg","@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#mainImage","width":1200,"height":675},"primaryImageOfPage":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/#mainImage"},"datePublished":"2024-09-02T07:30:12+02:00","dateModified":"2024-09-02T09:46:05+02:00"},{"@type":"WebSite","@id":"https:\/\/naturbett-einstreu.ch\/fr\/#website","url":"https:\/\/naturbett-einstreu.ch\/fr\/","name":"Naturbett\u00ae Einstreu","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/naturbett-einstreu.ch\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Naturbett\u00ae Einstreu |","og:type":"article","og:title":"Lit naturel\u00ae liti\u00e8re pour chevaux \u00e0 Cheval Passion 2024 | Naturbett\u00ae Einstreu","og:url":"https:\/\/naturbett-einstreu.ch\/fr\/lit-naturel-litiere-pour-chevaux-a-cheval-passion-2024\/","og:image":"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2021\/05\/naturbett-pferdeeinstreu.jpg","og:image:secure_url":"https:\/\/naturbett-einstreu.ch\/wp-content\/uploads\/2021\/05\/naturbett-pferdeeinstreu.jpg","og:image:width":1640,"og:image:height":856,"article:published_time":"2024-09-02T05:30:12+00:00","article:modified_time":"2024-09-02T07:46:05+00:00"},"aioseo_meta_data":{"post_id":"6742","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-15 07:52:21","updated":"2025-06-26 12:02:16","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/posts\/6742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/comments?post=6742"}],"version-history":[{"count":0,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/posts\/6742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/media\/6744"}],"wp:attachment":[{"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/media?parent=6742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/categories?post=6742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturbett-einstreu.ch\/fr\/wp-json\/wp\/v2\/tags?post=6742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}